{"id":4037,"date":"2018-06-26T18:26:21","date_gmt":"2018-06-26T18:26:21","guid":{"rendered":"http:\/\/corretoraideal.com.br\/blog\/index.php\/2018\/06\/26\/cca_title\/"},"modified":"2018-06-26T18:27:11","modified_gmt":"2018-06-26T18:27:11","slug":"um-quarto-com-o-cara-que-vive-em-ti-decorviva","status":"publish","type":"post","link":"https:\/\/blog.corretoraideal.com.br\/index.php\/2018\/06\/26\/um-quarto-com-o-cara-que-vive-em-ti-decorviva\/","title":{"rendered":"Um quarto com o cara que vive em ti! \u2013 Decorviva"},"content":{"rendered":"<p>Quando olhamos para este pequeno quarto bonito n&atilde;o pode imaginar os dias de marasmo, que ela j&aacute; viveu.<\/p>\n<p>Os moradores sempre soube que eles precisavam tomar alguma a&ccedil;&atilde;o com rela&ccedil;&atilde;o a decora&ccedil;&atilde;o, mas onde est&aacute; a coragem?<\/p>\n<p>Muitas vezes, o fato de as pessoas n&atilde;o saber por onde come&ccedil;ar &eacute; com a gente para manter as coisas como elas s&atilde;o, mesmo quando esse sentimento de desconforto insiste em viver diariamente com a gente.<\/p>\n<p>Mas esperar para ser feliz dentro de nosso pr&oacute;prio ninho se a vida acontece no presente momento, hein? J&aacute; parou para pensar sobre isso? #filosofei<\/p>\n<p>Provavelmente foi bug do &#8220;AGORA VAI!&#8221;, o respons&aacute;vel por esta decis&atilde;o!<\/p>\n<p>Que bom! A vida &eacute; muito mais divertido quando vivemos em um espa&ccedil;o que nos representa e nos abra&ccedil;a. Algu&eacute;m a&iacute; discorda? ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4039\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/1-decorviva-1.jpeg\" alt=\"1 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Agora que voc&ecirc; j&aacute; viu a beleza da sala, entregue atrav&eacute;s do nosso <strong><a href=\"https:\/\/decorviva.com.br\/trato-na-casa\">Trato na Casa<\/a><\/strong>, que tal dar uma olhada na &#8220;beleza&#8221; da sala que recebemos?! Hehehe<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4040\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/antes-decorviva1.jpeg\" alt=\"antes decorviva1\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Em dois dias, eu disse DOIS DIAS, tudo mudou&#8230; E &eacute; muuuito melhor!!!<\/p>\n<h2>Vamos conferir juntos todas as solu&ccedil;&otilde;es que n&oacute;s sugerimos para o espa&ccedil;o? Esquerda!<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4041\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/4-decorviva-1.jpeg\" alt=\"4 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>No caso desta pequena sala, o casal de moradores s&oacute; tinha mesmo um sof&aacute;! S&oacute;!<\/p>\n<p>Ent&atilde;o, vamos tomar muito cuidado com este item como importante, e criar uma capa super ajustadinha, produzido em um tecido de jeans bem molinho e aconchegante. O sof&aacute; antigo transformado em outro, muito mais feliz!<\/p>\n<p>Tamb&eacute;m havia um pequeno m&oacute;vel que armazenar qualquer baguncinha e s&oacute;!!! Escolhemos para iniciar a partir do zero e colocar tudo de novo, e, especialmente, para criar uma &aacute;rea de jantar, bonito e bem iluminado, o verdadeiro sonho de consumo da fam&iacute;lia.<\/p>\n<p>N&oacute;s instalado cortina rol&ocirc; na janela, podemos substituir a ilumina&ccedil;&atilde;o geral que ele era apenas um ponto central para um trilho eletrificado com quatro pontos PAR 20 Led. Que diferen&ccedil;a!<\/p>\n<p>Para a conta da planta atrav&eacute;s de complicadas, n&oacute;s escolhemos o canto generoso para o lado da porta de entrada, para colocar a mesa de jantar. Como ela n&atilde;o iria ser usado, muitas vezes, optamos por mant&ecirc;-lo contra o dia-a-dia, para servir como mesa de estudos para a filha do casal. Para deixar mais despojado, n&oacute;s escolhemos o branco cadeiras de diferentes modelos.<\/p>\n<p>(Mesa de jantar por Fernando Jaeger, pingente Dimlux, hist&oacute;rias em Quadrinhos criadas por n&oacute;s, a tabela de lado, e o banco sob a janela da Tok Stok)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4042\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/5-decorviva.jpeg\" alt=\"5 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Depois de criar este canto da sala de jantar\/estudo, pincelamos o espa&ccedil;o com pe&ccedil;as bacanas e cheias de bom humor. O destaque para a lumin&aacute;ria de ch&atilde;o, almofadas coloridas, fezes, que servem como mesas de centro, todos os da <strong><a href=\"http:\/\/www.casamind.com.br\/\">Casa de Mente<\/a><\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4043\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/6-decorviva-1.jpeg\" alt=\"6 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4044\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/7-decorviva-1.jpeg\" alt=\"7 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4045\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/8-decorviva-1.jpeg\" alt=\"8 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Na parede que vai para o corredor dos quartos, colocar um carrinho &eacute; super vers&aacute;til, serve como visitante, o canto do caf&eacute;, a biblioteca e o que mais voc&ecirc; imaginar. M&oacute;veis curingas s&atilde;o os nossos favoritos! Esta beleza da foto tamb&eacute;m veio da <strong><a href=\"http:\/\/www.casamind.com.br\/\">Casa da Mente<\/a><\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4046\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/9-decorviva-1.jpeg\" alt=\"9 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Na foto abaixo voc&ecirc; v&ecirc; o lado oposto do sof&aacute;, que tamb&eacute;m foi super harm&ocirc;nico e limpo. Escolhemos para agilizar o processo de compra e buscar todos os produtos na mesma loja, pronta entrega. O Rack, o tapete e a l&acirc;mpada (o que lan&ccedil;a luz para a linda R&aacute;fia comprado na Cadeg) veio da Tok Stok .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4047\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/11-decorviva-1.jpeg\" alt=\"11 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>O ch&atilde;o da samambaia e o cachep&ocirc; torcida que acompanha o R&aacute;fia s&atilde;o da <strong><a href=\"http:\/\/www.casamind.com.br\/\">Casa de Mente<\/a><\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4048\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/12-decorviva-1.jpeg\" alt=\"12 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Pontuamos a decora&ccedil;&atilde;o com alguns toques de preto para dar um muito contempor&acirc;neo e moderninho para a sala de estar. Para tornar o conjunto mais acolhedor e convidativo, pincelamos o espa&ccedil;o com pe&ccedil;as em madeira e fibras naturais, um grande recurso para que o ambiente n&atilde;o fique &#8220;frio&#8221; e impessoal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4049\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/13-decorviva.jpeg\" alt=\"13 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Sutilmente, o jeans e o sof&aacute; coordena com o enredo de fezes artesanal da <a href=\"http:\/\/www.casamind.com.br\/\">Casa da Mente<\/a>. Nada &eacute; por acaso meus amigos&#8230;nada, nada! ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4050\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/14-decorviva.jpeg\" alt=\"14 decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Simplesmente apaixonado pela mesa de jantar (Fernando Jaeger) que ganhou um tampo de vidro para torn&aacute;-lo ainda mais protegido no dia-a-dia. Temos um canto bem tirada e iluminado, o que pode ser facilmente ampliado quando eles conseguir mais visitas para o jantar. Apenas desencostar o quadro da parede e acomodar at&eacute; 8 pessoas! Uau!!!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4051\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/img-7984.jpeg\" alt=\"IMG 7984\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>O tamborete de etapa encantador que voc&ecirc; receber o cobertor, o revisteiro e o centro da mesa tamb&eacute;m s&atilde;o da <a href=\"http:\/\/www.casamind.com.br\/\">Casa de Mente<\/a>.<\/p>\n<h2>Vamos ver mais um &#8220;resum&atilde;o&#8221; da transforma&ccedil;&atilde;o? ?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4052\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/antes-decorviva2.jpeg\" alt=\"antes decorviva2\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<h2>Mas antes de terminar, os DETALHES, sempre eles&#8230;.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4053\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/montagem-decorviva.jpeg\" alt=\"montagem decorviva\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<p>Eu te enganar n&atilde;o&#8230; seria f&aacute;cil f&aacute;cil viver neste pequeno espa&ccedil;o!!!<\/p>\n<p>E voc&ecirc;? Conta l&aacute;! ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4054\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/06\/jpeg-para-posts-2.jpeg\" alt=\"jpeg para posts\" width=\"800\" height=\"400\" \/><\/img><\/p>\n<h3>Coment&aacute;rios<\/h3>\n<p> Coment&aacute;rios<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando olhamos para este pequeno quarto bonito n&atilde;o pode imaginar os dias de marasmo, que ela j&aacute; viveu. Os moradores sempre soube que eles precisavam tomar alguma a&ccedil;&atilde;o com rela&ccedil;&atilde;o a decora&ccedil;&atilde;o, mas onde est&aacute; a coragem? Muitas vezes, o fato de as pessoas n&atilde;o saber por onde come&ccedil;ar &eacute; com a gente para manter [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4037","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4037"}],"version-history":[{"count":1,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4037\/revisions"}],"predecessor-version":[{"id":4055,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4037\/revisions\/4055"}],"wp:attachment":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}