{"id":4824,"date":"2018-07-04T07:22:57","date_gmt":"2018-07-04T07:22:57","guid":{"rendered":"http:\/\/corretoraideal.com.br\/blog\/index.php\/2018\/07\/04\/cca_title\/"},"modified":"2018-07-04T07:23:17","modified_gmt":"2018-07-04T07:23:17","slug":"a-justica-do-rio-impede-que-um-municipio-em-crise-para-passar-a-mostrar-anitta-exame","status":"publish","type":"post","link":"https:\/\/blog.corretoraideal.com.br\/index.php\/2018\/07\/04\/a-justica-do-rio-impede-que-um-municipio-em-crise-para-passar-a-mostrar-anitta-exame\/","title":{"rendered":"A justi\u00e7a do Rio impede que um munic\u00edpio em crise para passar a mostrar Anitta | exame"},"content":{"rendered":"<p><\/img><\/p>\n<p>Anitta: manter o arrendamento de atrac&ccedil;&otilde;es, tais como Anitta, Alexandre Pires e Luan Santana (Facebook de Anitta\/detec&ccedil;&atilde;o)<\/p>\n<p>A justi&ccedil;a <strong><a href=\"https:\/\/exame.abril.com.br\/noticias-sobre\/rio-de-janeiro\/\" target=\"_blank\" rel=\"noopener\">do Rio<\/a><\/strong> proibiu o munic&iacute;pio de Itagua&iacute;, na regi&atilde;o metropolitana do Rio de janeiro pagamento de despesas de mais de a festa conhecida como Itagua&iacute; 2018 est&aacute; prevista para come&ccedil;ar amanh&atilde; (4), que comemora 200 anos da cidade. Na a&ccedil;&atilde;o civil p&uacute;blica, com pedido de necessidade urgente de anteced&ecirc;ncia, proposta pelo minist&eacute;rio p&uacute;blico do Rio (MPRJ).<\/p>\n<p>O munic&iacute;pio enfrenta problemas na rede de sa&uacute;de p&uacute;blica, na educa&ccedil;&atilde;o da cidade, com muitas escolas fechadas. O principal Hospital de Itagua&iacute;, San Francisco Javier chegou &agrave; emerg&ecirc;ncia de fechar devido &agrave; falta de recursos de atendimento de emerg&ecirc;ncia da unidade (UPA) de Itagua&iacute; n&atilde;o est&aacute; funcionando.<\/p>\n<p>O juiz Richard Robert Fairclough, a 2&ordf; vara Civil da regi&atilde;o de Itagua&iacute;, deferiu o pedido de liminar, determinando que a gest&atilde;o de Itagua&iacute;, a abster-se de qualquer pagamento devido &agrave;s despesas relacionadas com a celebra&ccedil;&atilde;o do anivers&aacute;rio do munic&iacute;pio, com apresenta&ccedil;&otilde;es de artistas famosos de 4 a 8 de julho. Os gastos devem ser imediatamente suspensa, sob pena de aplica&ccedil;&atilde;o de multa pessoal da autoridade administrativa no valor de 30% do valor pago.<\/p>\n<p>De acordo com a a&ccedil;&atilde;o civil p&uacute;blica, apesar da import&acirc;ncia das restri&ccedil;&otilde;es de or&ccedil;amento, a administra&ccedil;&atilde;o municipal realizou cr&eacute;dito adicional de R $ 1,8 milh&atilde;o para a Secretaria municipal de eventos, a fim de cobrir o ano de 2018. Al&eacute;m da crise, o Prefeito Carlos Busatto J&uacute;nior, o Charlinho mulheres Andrea &eacute; o Secret&aacute;rio de Educa&ccedil;&atilde;o de Itagua&iacute;, na R&uacute;ssia, assistindo a Copa do Mundo. Em um comunicado, o Prefeito disse que ele j&aacute; voltou da viagem.<\/p>\n<h3>Financeira desgra&ccedil;a<\/h3>\n<p>Na investiga&ccedil;&atilde;o iniciada na investiga&ccedil;&atilde;o de uma reclama&ccedil;&atilde;o sobre o alto custo do evento, o governo municipal apresentou os procedimentos administrativos que descrevem as despesas de R $ 6,2 milh&otilde;es no aluguer de atra&ccedil;&otilde;es tur&iacute;sticas, tais como <strong><a href=\"https:\/\/exame.abril.com.br\/noticias-sobre\/anitta\/\" target=\"_blank\" rel=\"noopener\">Anitta<\/a><\/strong>, Alexandre Pires e Luan Santana, al&eacute;m de pagar por servi&ccedil;os de infra-estrutura.<\/p>\n<p>De acordo com o MPRJ, n&atilde;o s&oacute; para o alto custo de concertos programados na cidade envolvido em um leg&iacute;timo parar o pagamento de 50% do sal&aacute;rio para os artistas. O mesmo governo tinha declarado um estado de desastre financeiro, a fim de controlar a cidade no in&iacute;cio de 2017, alegando que a receita n&atilde;o &eacute; feita por administra&ccedil;&otilde;es anteriores deixaram um buraco nas contas do munic&iacute;pio no res&iacute;duo de d&iacute;vida.<\/p>\n<p>Enquanto a cidade gastou milh&otilde;es para o partido, a justi&ccedil;a concedeu liminares contra a cidade, exigem a&ccedil;&atilde;o imediata para corrigir problemas graves na rede de cuidados de sa&uacute;de. Nenhum dos seis foram cumpridos, afirmam que haver&aacute; fundos dispon&iacute;veis em caixa para tais medidas.<\/p>\n<h3>&#8220;Situa&ccedil;&atilde;o tr&aacute;gica&#8221;<\/h3>\n<p>Na decis&atilde;o do juiz Richard Fairclough, escreveu que &#8220;a Assembl&eacute;ia Geral e, ainda, permitir amplamente na m&iacute;dia, a tr&aacute;gica situa&ccedil;&atilde;o financeira de Itagua&iacute;, com um impacto direto sobre os sal&aacute;rios dos servidores nas escolas, principalmente na rede de sa&uacute;de do pa&iacute;s.&#8221; Ainda de acordo com a regra antes de tal situa&ccedil;&atilde;o, foi o Decreto do estado de calamidade no pa&iacute;s, exigindo prioridade de gastos em &#8220;necessidades sociais&#8221;.<\/p>\n<p>O juiz tamb&eacute;m observou que o auto-governo decide gastar, n&atilde;o tem limites. &#8220;Al&eacute;m das quest&otilde;es t&eacute;cnicas, financeiras e or&ccedil;ament&aacute;rias, deve-se verificar se o gasto &eacute; apropriado com a finalidade de interesse p&uacute;blico. Discri&ccedil;&atilde;o n&atilde;o &eacute; uma mensagem vazia nas m&atilde;os do administrador. Todos os procedimentos devem ser o norte do interesse p&uacute;blico, incluindo os direitos individuais e sociais b&aacute;sicos&#8221;, disse ele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anitta: manter o arrendamento de atrac&ccedil;&otilde;es, tais como Anitta, Alexandre Pires e Luan Santana (Facebook de Anitta\/detec&ccedil;&atilde;o) A justi&ccedil;a do Rio proibiu o munic&iacute;pio de Itagua&iacute;, na regi&atilde;o metropolitana do Rio de janeiro pagamento de despesas de mais de a festa conhecida como Itagua&iacute; 2018 est&aacute; prevista para come&ccedil;ar amanh&atilde; (4), que comemora 200 anos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4824","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4824"}],"version-history":[{"count":1,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4824\/revisions"}],"predecessor-version":[{"id":4826,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4824\/revisions\/4826"}],"wp:attachment":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}