{"id":4981,"date":"2018-07-05T22:23:04","date_gmt":"2018-07-05T22:23:04","guid":{"rendered":"http:\/\/corretoraideal.com.br\/blog\/index.php\/2018\/07\/05\/cca_title\/"},"modified":"2018-07-05T22:23:25","modified_gmt":"2018-07-05T22:23:25","slug":"instalacao-eletrica-aparente-do-edu","status":"publish","type":"post","link":"https:\/\/blog.corretoraideal.com.br\/index.php\/2018\/07\/05\/instalacao-eletrica-aparente-do-edu\/","title":{"rendered":"Instala\u00e7\u00e3o El\u00e9trica Aparente Do Edu"},"content":{"rendered":"<p>Tem sido um tempo que eu estou e este post, certo? Eu usei essa t&eacute;cnica no velho escrit&oacute;rio em casa, mas acabei por me mover antes do final. Ent&atilde;o eu decidi fazer no escrit&oacute;rio da casa nova.<\/p>\n<p>A instala&ccedil;&atilde;o de electricidade, a aparente &eacute; muito bom e deixa a casa com uma pegada de ind&uacute;stria. Tudo come&ccedil;ou na d&eacute;cada de 50, em Nova York, quando algumas f&aacute;bricas foram transformadas em im&oacute;veis residenciais e os caras perceberam que, tendo o tubo exposto poderia ser algo legal. Atualmente, tem as tomadas, os interruptores e as tubula&ccedil;&otilde;es expostas &eacute; figurinha carimbada em ambientes que s&atilde;o mais modernos, bem como de tijolo e cimento aparente.<\/p>\n<p>Ent&atilde;o vamos para o material b&aacute;sico:<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_110.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4983\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-1.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 1\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<li>Eletroduto de 3\/4 (em a&ccedil;o galvanizado ou alum&iacute;nio) a 10,00 (barra c\/ 3 metros)<\/li>\n<li>Unidut ou Manga 3\/4 &ndash; 2,00<\/li>\n<li>Curva para eletroduto &ndash; 6,00<\/li>\n<li>Clamp &ndash; 0,50<\/li>\n<li>Condulete &ndash; 6,00<\/li>\n<li>Tomada e interruptor &ndash; 5,50 cada<\/li>\n<p>O primeiro passo &eacute; criar a estrutura que voc&ecirc; precisa defini&ccedil;&atilde;o de quantas tomadas, interruptores e lumin&aacute;rias que voc&ecirc; deseja instalar. Depois de cortar a conduit nos tamanhos que voc&ecirc; precisa. Us&aacute;-lo como refer&ecirc;ncia para marcar o local onde ser&aacute; fixado o cabo de grampos. Vale lembrar que para cada metro de conduta, voc&ecirc; precisar de um grampo para anexar ok?<\/p>\n<p><a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4984\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-2.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 2\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4985\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-3.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 3\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4986\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-4.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 4\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4987\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-5.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 5\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<p>Agora fa&ccedil;a um buraco na parte de tr&aacute;s do condulete usando broca para metal. Depois de desmontar o interruptor (com a eletricidade desligada, por favor), de onde v&atilde;o sair os fios e passe-os para esta nova caixa. Em seguida, encaixe o conduto de sa&iacute;da de condulete, parafuso e segura o grampo.<\/p>\n<p><a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4988\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-6.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 6\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4989\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-7.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 7\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<p>Esse &eacute; o b&aacute;sico da instala&ccedil;&atilde;o. Agora &eacute; s&oacute; ir em adicionar como muitos conduletes que voc&ecirc; precisa, de fus&atilde;o com a conduit.<\/p>\n<p>Pros cantos, use a curva de alum&iacute;nio. Para prend&ecirc;-lo &agrave; conduit, use um unidut (ou manga). No meu caso, eu usei a curva para passar a fia&ccedil;&atilde;o pro teto, onde voc&ecirc; vai sair de uma lumin&aacute;ria.<\/p>\n<p><a href=\"https:\/\/i2.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4990\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-8.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 8\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4991\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-9.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 9\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4992\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-10.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 10\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4993\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-11.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 11\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<p>Com a estrutura b&aacute;sica pronta, agora &eacute; s&oacute; fazer a instala&ccedil;&atilde;o el&eacute;trica. Passar o fio paralelo em torno da conduit e faz liga&ccedil;&otilde;es normalmente. Vale lembrar que, se voc&ecirc; vai instalar a lumin&aacute;ria, voc&ecirc; precisa de um thread s&oacute; para ele e o switch e outro para tomadas.<\/p>\n<p><strong>Se voc&ecirc; n&atilde;o entende nada el&eacute;trica, seja esperto e pe&ccedil;a ajuda. N&atilde;o tomar choque &eacute; ruim.<\/strong><\/p>\n<p><a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4994\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-13.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 13\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i2.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_14.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4995\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-14.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 14\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<p>Depois de fazer as conex&otilde;es e, em seguida, feche todas as de alum&iacute;nio. Para manter a luz, eu fiz um buraco em uma placa de cobertura para onde eu passei o fio e deu um n&oacute;. Eu fiz a conex&atilde;o el&eacute;trica normalmente. Voc&ecirc; v&ecirc; o resultado:<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4996\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-15.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 15\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i0.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4997\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-16.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 16\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i2.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_17.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4998\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-17.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 17\" width=\"800\" height=\"400\" \/><\/img><\/a> <a href=\"https:\/\/i1.wp.com\/homensdacasa.net\/wp-content\/uploads\/2015\/03\/instala&ccedil;&atilde;o_aparente_18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4999\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/instalacao-aparente-18.jpeg\" alt=\"instala&ccedil;&atilde;o aparente 18\" width=\"800\" height=\"400\" \/><\/img><\/a><\/p>\n<p> Todo o material voc&ecirc; encontra em lojas de material el&eacute;trico. Se voc&ecirc; &eacute; de BH, voc&ecirc; pode ir no Othon de Carvalho ou de Armazenamento El&eacute;trico.<\/p>\n<p> Nunca misture cabos de rede, de internet e de telefone, cabos, electricity ok? Use um eletroduto para cada um.<\/p>\n<p> N&atilde;o se esque&ccedil;a de sempre fazer um esquemy antes com a quantidade de tomadas e interruptores que voc&ecirc; vai precisar.<\/p>\n<p> A luz pendant tem na <a href=\"http:\/\/www.hcstore.net\/pd-f208f-pendente-industrial.html?ct=70f31&amp;p=1&amp;s=1\">loja do blog<\/a> com pre&ccedil;o super bom. <a href=\"http:\/\/www.hcstore.net\/pd-f208f-pendente-industrial.html?ct=70f31&amp;p=1&amp;s=1\"><strong>N&atilde;o que voc&ecirc; v&aacute;!<\/strong><\/a><\/p>\n<p>Ah, &eacute; o video com o passo-a-passo. Olha s&oacute;:<\/p>\n<\/p>\n<p>Apesar de ter uma pegada industrial, este tipo de instala&ccedil;&atilde;o pode ser feita em qualquer ambiente. Se voc&ecirc; mistura com outro estilo &eacute; muito agrad&aacute;vel a composi&ccedil;&atilde;o. No meu caso, o escrit&oacute;rio tem uma decora&ccedil;&atilde;o mais moderna e contempor&acirc;nea, e os tubos de metal exposto deu a pegada industrial que eu precisava.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tem sido um tempo que eu estou e este post, certo? Eu usei essa t&eacute;cnica no velho escrit&oacute;rio em casa, mas acabei por me mover antes do final. Ent&atilde;o eu decidi fazer no escrit&oacute;rio da casa nova. A instala&ccedil;&atilde;o de electricidade, a aparente &eacute; muito bom e deixa a casa com uma pegada de ind&uacute;stria. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4981","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4981"}],"version-history":[{"count":1,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4981\/revisions"}],"predecessor-version":[{"id":5000,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4981\/revisions\/5000"}],"wp:attachment":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}