{"id":5069,"date":"2018-07-06T19:24:06","date_gmt":"2018-07-06T19:24:06","guid":{"rendered":"http:\/\/corretoraideal.com.br\/blog\/index.php\/2018\/07\/06\/cca_title\/"},"modified":"2018-07-06T19:24:44","modified_gmt":"2018-07-06T19:24:44","slug":"com-meireles-mdb-enfrentar-o-desafio-de-manter-um-pedido-nacional-exame","status":"publish","type":"post","link":"https:\/\/blog.corretoraideal.com.br\/index.php\/2018\/07\/06\/com-meireles-mdb-enfrentar-o-desafio-de-manter-um-pedido-nacional-exame\/","title":{"rendered":"Com Meireles, MDB enfrentar o desafio de manter um pedido nacional | exame"},"content":{"rendered":"<p><\/img><\/p>\n<p>Henrique meirelles: o grau de confian&ccedil;a na capacidade de crescimento antes de o candidato tem diminu&iacute;do em parte (Adriano Machado\/Reuters)<\/p>\n<p>Bras&iacute;lia &ndash; <strong><a href=\"https:\/\/exame.abril.com.br\/noticias-sobre\/pmdb\">o MDB<\/a><\/strong> anunciou com pompa, no final de Maio, antes da nomea&ccedil;&atilde;o do antigo Ministro das Finan&ccedil;as Henrique meirelles para a presid&ecirc;ncia, mas, menos de um m&ecirc;s do final do prazo para a festa na piscina ainda n&atilde;o sabemos, agora, que caminho tomar, e mesmo se fosse para disseminar a id&eacute;ia de finalmente ter um candidato pr&oacute;prio, pela primeira vez, em 24 anos para confirmar.<\/p>\n<p>Fontes ouvidas pela Reuters confirma que a id&eacute;ia de um filtro para a parte chamada entusiasmados no in&iacute;cio, emedebistas &ndash;especialmente aqueles que vai pagar a minha prote&ccedil;&atilde;o, mas a estagna&ccedil;&atilde;o do Meireles, em 1% das inten&ccedil;&otilde;es de voto esfria raiva.<\/p>\n<p>&#8220;Hoje, se votar na Conven&ccedil;&atilde;o n&atilde;o aprovar (aplica&ccedil;&atilde;o)&#8221;, disse &agrave; Reuters citou uma fonte pr&oacute;xima ao topo do partido.<\/p>\n<p>Isso explica por que, quando, esta semana, na &uacute;ltima reuni&atilde;o da Diretoria Executiva, do ex-deputado Jo&atilde;o Henrique Sousa coordenador da pol&iacute;tica <strong><a href=\"https:\/\/exame.abril.com.br\/noticias-sobre\/henrique-meirelles\/\">Meireles<\/a><\/strong>prop&ocirc;s 31 de julho de data para a Conven&ccedil;&atilde;o que confirmar ou n&atilde;o a Aplica&ccedil;&atilde;o, Presidente do partido, Senador Romero Juc&aacute; (RR), desconversou. Mesmo agora que a festa n&atilde;o se sabe quando voc&ecirc; quer fazer.<\/p>\n<p>&#8220;Voc&ecirc; n&atilde;o tem consenso hoje sobre o que precisa ser feito. C&uacute;pula est&aacute; a tentar construir um acordo, mas o partido est&aacute; perdidinho&#8221;, disse uma fonte pr&oacute;xima do Ministro.<\/p>\n<p>Meireles passou os seus dias de reuni&otilde;es com as regionais partes. J&aacute; passou por uma grande parte do nordeste e Centro-Oeste e alguns Estados do Norte do pa&iacute;s para avaliar os l&iacute;deres da regi&atilde;o e convenc&ecirc;-los de que voc&ecirc; tem oportunidades de crescimento.<\/p>\n<p>&#8220;Em alguns casos, a ideia de MP conservador candidato de que voc&ecirc; vai ser capaz de dizer que o eleitor vote 15 (O n&uacute;mero do MDB), de cima para baixo, aderem bem, eles s&atilde;o como,&#8221; diz uma fonte pr&oacute;xima do Ministro, mas sem mostrar muito entusiasmo com o resultado.<\/p>\n<p>Na mesma reuni&atilde;o, a ba&iacute;a apelo aos presentes para apoiar a candidatura de Meireles. O senador tenta costurar um acordo para fornecer filtragem para a Conven&ccedil;&atilde;o, sem o risco de resultados negativos.<\/p>\n<h3>A prote&ccedil;&atilde;o de menos<\/h3>\n<p>Um entusiasta de primeira hora da aplica&ccedil;&atilde;o do Meireles, Bay disse em conversas com aliados e parceiros cen&aacute;rio pol&iacute;tico s&atilde;o muito indefinido, e que pelo candidato do partido vai fazer o rosto do plano como um &#8220;radical&#8221; do centro. E que Meireles tem um monte de espa&ccedil;o na m&iacute;dia ir&atilde;o crescer logo que anunciou oficialmente os candidatos.<\/p>\n<p>O grau de confian&ccedil;a na capacidade de crescimento, no entanto, tem diminu&iacute;do no partido. No in&iacute;cio, os entusiastas de Meireles para dizer que ele seria o candidato pode chegar at&eacute; 10 pontos percentuais. No momento de uma tarde de um desafio de 5 por cento.<\/p>\n<p>Agora, a avalia&ccedil;&atilde;o &eacute; apenas n&atilde;o fazer o &#8220;movimento de crescimento&#8221;, erguendo-se do ponto de incandesc&ecirc;ncia 1 a 2 a 3 por cento. Previs&atilde;o &eacute; muito otimista.<\/p>\n<p>&#8220;N&atilde;o vai acontecer. N&atilde;o h&aacute; nenhuma evid&ecirc;ncia de que uma das fontes.<\/p>\n<p>O Presidente de solidariedade, uma das partes &eacute; chamado bloc&atilde;o dos partidos de centro, Mr. paolini for&ccedil;a), andando na mesma linha diz que a nomea&ccedil;&atilde;o do ex-Ministro da fazenda n&atilde;o tem nenhuma chance de sucesso.<\/p>\n<p>&#8220;N&atilde;o, &eacute; vinculada ao governo vai ser o maior perdedor desta elei&ccedil;&atilde;o&#8221;, disse paulinho. &#8220;Colar em governo, morreu.&#8221;<\/p>\n<p>A solidariedade &eacute; uma das partes do bloc&atilde;o que se afastaram politicamente do governo tendem a apoiar nas elei&ccedil;&otilde;es de outubro a candidatura de centro-esquerda, o ex-Ministro Ciro Gomes, do PDT.<\/p>\n<h3>O governo do medo<\/h3>\n<p>Na campanha Meireles, de classifica&ccedil;&otilde;es, de acordo com a fonte, &eacute; de que o Ministro da luta, n&atilde;o s&oacute; com seus pr&oacute;prios problemas, como os eleitores da minha falta de carisma, mas contra o Governo do Presidente <strong><a href=\"https:\/\/exame.abril.com.br\/noticias-sobre\/michel-temer\">Michel Temer<\/a><\/strong>. Pela primeira vez na hist&oacute;ria moderna, para ser o candidato do governo &eacute; um grande problema, n&atilde;o ajuda.<\/p>\n<p>Com a rejei&ccedil;&atilde;o de mais de 80 por cento, o governo do medo &eacute; um dos pontos fracos na aplica&ccedil;&atilde;o de Meireles. No entanto, quando o Ministro tentou afastar-se, dizendo que ele n&atilde;o &eacute; um &#8220;candidato de mercado, o governo do candidato ou candidatos de Bras&iacute;lia&#8221; ouvi as queixas.<\/p>\n<p>Depois de o Ministro est&aacute; tentando se distanciar do pr&oacute;prio Presidente, com foco na defesa do governo na economia, e seu trabalho no Minist&eacute;rio das Finan&ccedil;as. A maioria vai tentar lembrar os eleitores de que ele era o Presidente do Banco Central no Governo de Luiz In&aacute;cio Lula da Silva &ndash;que, t&atilde;o preso ainda no primeiro lugar nas pesquisas&ndash; e, em seguida, chamar a si mesmo, sem vergonha, todo o sucesso econ&ocirc;mico, o Governo da petista.<\/p>\n<p>Dentro do planalto, com o pagamento ou n&atilde;o de medo da maioria posi&ccedil;&atilde;o, incluindo o Presidente, &eacute; manter-se sobre a nomea&ccedil;&atilde;o do ex-Ministro.<\/p>\n<p>&#8220;MDB tinha perdido a vantagem do Nacional, a falta de aplicativos nativos. Precisamos defender o projeto, mostra as id&eacute;ias do partido, tomar um cara com o Nacional do MDB&#8221;, disse a fonte.<\/p>\n<p>A cr&iacute;tica &eacute; que o Partido se transformou em um conjunto de feudos regionais, que ser&aacute; de Rennes Calheiros, em alagoas, o desafio do medo e aliado de primeira hora do PT&#8221;, sem a&#8221; defesa alian&ccedil;as com o tucano geraldo Alckmin ou fazer acordos informais com Ciro Gomes (PDT), o Presidente do Senado, Eun&iacute;cio Oliveira, candidato para o Senado no estado do Cear&aacute;, a base eleitoral do pedetista. Aplicativo que vai ajudar a dar a vantagem para o Partido Nacional, mesmo com todas as divis&otilde;es internas.<\/p>\n<p>No entanto, n&atilde;o h&aacute; consenso sobre o curso do partido. Avaliar a fonte da c&uacute;pula do partido que se Meireles n&atilde;o &eacute; o nome do partido, o MDB tornar-se independente na primeira rodada vai combinar aplicativos ou projetos que eleger a marca ou a marca.<\/p>\n<p>&#8220;MDB pronto para ganhar com Meireles ou ser uma for&ccedil;a independente&#8221;, disse uma fonte da c&uacute;pula da legenda.<\/p>\n<p>J&aacute; tradicional, o senador do MDB que a melhor legenda para abandonar a aplica&ccedil;&atilde;o de Meireles e configurar com o tucano geraldo Alckmin. &#8220;Voc&ecirc; deve ir com ele&#8221;, disse o Presidente do partido.<\/p>\n<p>Esta coaliz&atilde;o, mas agora muito improv&aacute;vel. Duas fontes disseram &agrave; Reuters que n&atilde;o h&aacute; espa&ccedil;o para raz&otilde;es diferentes. Um luxo, diz que o governo n&atilde;o quer, desde que Alckmin se afastou de medo e faz cr&iacute;ticas dif&iacute;cil para o governo. Outra campanha associada Meireles diz que h&aacute; at&eacute; mesmo um funeral tucana eu gostaria de falar, mas Alckmin &eacute; proibido em qualquer conversa.<\/p>\n<p>Veja tamb&eacute;m<\/p>\n<ul>\n<li><a class=\"widget-news-thumb mini\" href=\"https:\/\/exame.abril.com.br\/brasil\/meirelles-diz-que-pode-levar-votos-de-lula\/\" rel=\"bookmark\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5071\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/henrique-meirelleshenrique-meirelles.jpeg\" alt=\"Henrique MeirellesHenrique Meirelles\" width=\"800\" height=\"400\" \/><\/img><\/a><a href=\"\/brasil\" class=\"widget-news-item-category color-theme\">Brasil,<\/a><a href=\"https:\/\/exame.abril.com.br\/brasil\/meirelles-diz-que-pode-levar-votos-de-lula\/\" class=\"\">meirelles diz que ele pode tirar votos lol<\/a><i>query_builder<\/i> 4 de julho de 2018 &#8211; 16h07<\/li>\n<li><a class=\"widget-news-thumb mini\" href=\"https:\/\/exame.abril.com.br\/brasil\/se-eleito-meirelles-diz-que-fara-ampla-reforma-tributaria\/\" rel=\"bookmark\">enda, Henrique meirelles, falando com jornalistas em Bras&iacute;lia, o Brasil&#8221; width=&#8221;800&#8243; height=&#8221;400&#8243; \/&gt;<\/img><\/a><a href=\"\/brasil\" class=\"widget-news-item-category color-theme\">no Brasil, <\/a><a href=\"https:\/\/exame.abril.com.br\/brasil\/se-eleito-meirelles-diz-que-fara-ampla-reforma-tributaria\/\" class=\"\">se eleito, Meireles diz &#8220;mais ampla&#8221; reforma tribut&aacute;ria<\/a><i>query_builder<\/i> 4 de julho de 2018 &#8211; 15h07<\/li>\n<li><a class=\"widget-news-thumb mini\" href=\"https:\/\/exame.abril.com.br\/brasil\/alckmin-diz-que-nao-cogita-meirelles-como-vice\/\" rel=\"bookmark\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5073\" src=\"http:\/\/corretoraideal.com.br\/blog\/wp-content\/uploads\/2018\/07\/geraldo-alckmin-num-evento-em-nova-york-em-15mai2017.jpeg\" alt=\"Geraldo Alckmin num evento em Nova York, em 15\/mai\/2017\" width=\"800\" height=\"400\" \/><\/img><\/a><a href=\"\/brasil\" class=\"widget-news-item-category color-theme\">O brasil<\/a><a href=\"https:\/\/exame.abril.com.br\/brasil\/alckmin-diz-que-nao-cogita-meirelles-como-vice\/\" class=\"\">Alckmin diz que nem todos Meireles como Vice &#8211;<\/a><i>query_builder<\/i> 3 de julho de 2018 &#8211; 19h07<\/li>\n<li><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Henrique meirelles: o grau de confian&ccedil;a na capacidade de crescimento antes de o candidato tem diminu&iacute;do em parte (Adriano Machado\/Reuters) Bras&iacute;lia &ndash; o MDB anunciou com pompa, no final de Maio, antes da nomea&ccedil;&atilde;o do antigo Ministro das Finan&ccedil;as Henrique meirelles para a presid&ecirc;ncia, mas, menos de um m&ecirc;s do final do prazo para a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-5069","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5069"}],"version-history":[{"count":1,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5069\/revisions"}],"predecessor-version":[{"id":5074,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5069\/revisions\/5074"}],"wp:attachment":[{"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.corretoraideal.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}